{"id":8119,"date":"2026-07-01T15:41:49","date_gmt":"2026-07-01T12:41:49","guid":{"rendered":"https:\/\/tspride.com\/?post_type=model&#038;p=8119"},"modified":"2026-07-01T16:02:33","modified_gmt":"2026-07-01T13:02:33","slug":"dahiana-white","status":"publish","type":"model","link":"https:\/\/tspride.com\/de\/model\/dahiana-white\/","title":{"rendered":"DAHIANA WHITE"},"content":{"rendered":"<p data-path-to-node=\"3\"><b data-path-to-node=\"3\" data-index-in-node=\"0\">Dahiana White \u2013 Dein exklusives Latina-Erlebnis<\/b><\/p>\n<p data-path-to-node=\"4\">Lass dich verf\u00fchren&#8230; Ich bin Dahiana, eine stolze Kolumbianerin, die Sch\u00f6nheit und Leidenschaft in jeder Facette vereint. Als Content Creatorin stehe ich f\u00fcr \u00c4sthetik und Sinnlichkeit, doch pers\u00f6nlich bin ich noch viel faszinierender.<\/p>\n<p data-path-to-node=\"5\">Mein Service ist ein wahrer Genuss f\u00fcr Kenner. Ich biete dir keine allt\u00e4gliche Begegnung, sondern ein exklusives Erlebnis, bei dem deine W\u00fcnsche im Mittelpunkt stehen. Wenn du auf der Suche nach einer unvergesslichen Zeit bist, gepr\u00e4gt von nat\u00fcrlicher Eleganz und feurigem Temperament, dann bist du bei mir genau richtig. Ich freue mich darauf, dich kennenzulernen.<\/p>\n","protected":false},"featured_media":8117,"template":"","location":[34,32],"class_list":["post-8119","model","type-model","status-publish","has-post-thumbnail","hentry","location-berlin","location-germany"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DAHIANA WHITE - Trans Escort - TSPRIDE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tspride.com\/de\/model\/dahiana-white\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAHIANA WHITE - Trans Escort - TSPRIDE\" \/>\n<meta property=\"og:description\" content=\"Dahiana White \u2013 Dein exklusives Latina-Erlebnis Lass dich verf\u00fchren&#8230; Ich bin Dahiana, eine stolze Kolumbianerin, die Sch\u00f6nheit und Leidenschaft in jeder Facette vereint. Als Content Creatorin stehe ich f\u00fcr \u00c4sthetik und Sinnlichkeit, doch pers\u00f6nlich bin ich noch viel faszinierender. Mein Service ist ein wahrer Genuss f\u00fcr Kenner. Ich biete dir keine allt\u00e4gliche Begegnung, sondern ein [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tspride.com\/de\/model\/dahiana-white\/\" \/>\n<meta property=\"og:site_name\" content=\"TSPRIDE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T13:02:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png\" \/>\n\t<meta property=\"og:image:width\" content=\"684\" \/>\n\t<meta property=\"og:image:height\" content=\"844\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ProfilePage\"],\"@id\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/\",\"url\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/\",\"name\":\"DAHIANA WHITE - Trans Escort - TSPRIDE\",\"isPartOf\":{\"@id\":\"https:\/\/tspride.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png\",\"datePublished\":\"2026-07-01T12:41:49+00:00\",\"dateModified\":\"2026-07-01T13:02:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tspride.com\/de\/model\/dahiana-white\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/#primaryimage\",\"url\":\"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png\",\"contentUrl\":\"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png\",\"width\":684,\"height\":844},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tspride.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Germany\",\"item\":\"https:\/\/tspride.com\/germany\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Berlin\",\"item\":\"https:\/\/tspride.com\/berlin\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"DAHIANA WHITE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tspride.com\/de\/#website\",\"url\":\"https:\/\/tspride.com\/de\/\",\"name\":\"TSPRIDE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/tspride.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tspride.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tspride.com\/de\/#organization\",\"name\":\"TSPRIDE\",\"url\":\"https:\/\/tspride.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tspride.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tspride.com\/wp-content\/uploads\/2025\/06\/TSPRIDE.svg\",\"contentUrl\":\"https:\/\/tspride.com\/wp-content\/uploads\/2025\/06\/TSPRIDE.svg\",\"width\":160,\"height\":30,\"caption\":\"TSPRIDE\"},\"image\":{\"@id\":\"https:\/\/tspride.com\/de\/#\/schema\/logo\/image\/\"},\"mainEntityOfPage\":{\"@id\":\"https:\/\/tspride.com\/de\/model\/dahiana-white\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAHIANA WHITE - Trans Escort - TSPRIDE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tspride.com\/de\/model\/dahiana-white\/","og_locale":"de_DE","og_type":"article","og_title":"DAHIANA WHITE - Trans Escort - TSPRIDE","og_description":"Dahiana White \u2013 Dein exklusives Latina-Erlebnis Lass dich verf\u00fchren&#8230; Ich bin Dahiana, eine stolze Kolumbianerin, die Sch\u00f6nheit und Leidenschaft in jeder Facette vereint. Als Content Creatorin stehe ich f\u00fcr \u00c4sthetik und Sinnlichkeit, doch pers\u00f6nlich bin ich noch viel faszinierender. Mein Service ist ein wahrer Genuss f\u00fcr Kenner. Ich biete dir keine allt\u00e4gliche Begegnung, sondern ein [&hellip;]","og_url":"https:\/\/tspride.com\/de\/model\/dahiana-white\/","og_site_name":"TSPRIDE","article_modified_time":"2026-07-01T13:02:33+00:00","og_image":[{"width":684,"height":844,"url":"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ProfilePage"],"@id":"https:\/\/tspride.com\/de\/model\/dahiana-white\/","url":"https:\/\/tspride.com\/de\/model\/dahiana-white\/","name":"DAHIANA WHITE - Trans Escort - TSPRIDE","isPartOf":{"@id":"https:\/\/tspride.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tspride.com\/de\/model\/dahiana-white\/#primaryimage"},"image":{"@id":"https:\/\/tspride.com\/de\/model\/dahiana-white\/#primaryimage"},"thumbnailUrl":"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png","datePublished":"2026-07-01T12:41:49+00:00","dateModified":"2026-07-01T13:02:33+00:00","breadcrumb":{"@id":"https:\/\/tspride.com\/de\/model\/dahiana-white\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tspride.com\/de\/model\/dahiana-white\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tspride.com\/de\/model\/dahiana-white\/#primaryimage","url":"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png","contentUrl":"https:\/\/tspride.com\/wp-content\/uploads\/2026\/07\/Screenshot-2026-07-01-at-15.45.43.png","width":684,"height":844},{"@type":"BreadcrumbList","@id":"https:\/\/tspride.com\/de\/model\/dahiana-white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tspride.com\/"},{"@type":"ListItem","position":2,"name":"Germany","item":"https:\/\/tspride.com\/germany\/"},{"@type":"ListItem","position":3,"name":"Berlin","item":"https:\/\/tspride.com\/berlin\/"},{"@type":"ListItem","position":4,"name":"DAHIANA WHITE"}]},{"@type":"WebSite","@id":"https:\/\/tspride.com\/de\/#website","url":"https:\/\/tspride.com\/de\/","name":"TSPRIDE","description":"","publisher":{"@id":"https:\/\/tspride.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tspride.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tspride.com\/de\/#organization","name":"TSPRIDE","url":"https:\/\/tspride.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tspride.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/tspride.com\/wp-content\/uploads\/2025\/06\/TSPRIDE.svg","contentUrl":"https:\/\/tspride.com\/wp-content\/uploads\/2025\/06\/TSPRIDE.svg","width":160,"height":30,"caption":"TSPRIDE"},"image":{"@id":"https:\/\/tspride.com\/de\/#\/schema\/logo\/image\/"},"mainEntityOfPage":{"@id":"https:\/\/tspride.com\/de\/model\/dahiana-white\/"}}]}},"_links":{"self":[{"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/model\/8119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/model"}],"about":[{"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/types\/model"}],"version-history":[{"count":3,"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/model\/8119\/revisions"}],"predecessor-version":[{"id":8129,"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/model\/8119\/revisions\/8129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/media\/8117"}],"wp:attachment":[{"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/media?parent=8119"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/tspride.com\/de\/wp-json\/wp\/v2\/location?post=8119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}